{"id":2442,"date":"2019-03-28T10:45:00","date_gmt":"2019-03-28T10:45:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/blog\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/"},"modified":"2024-12-24T08:44:10","modified_gmt":"2024-12-24T08:44:10","slug":"toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica","status":"publish","type":"post","link":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/","title":{"rendered":"Toda &#038; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica"},"content":{"rendered":"<p>Toda &amp; Nel-lo, como firma de referencia en materia de contrataci\u00f3n p\u00fablica, y por medio de sus abogados de Derecho Administrativo <a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/jorge-pipaon-pulido\"><strong>Jorge Pipa\u00f3n <\/strong><\/a>y<strong> <a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/ma-antonieta-fernandez-lopez\">M\u00aa Antonieta Fern\u00e1ndez<\/a><\/strong>, particip\u00f3 en la <strong>VII jornada en materia de contrataci\u00f3n p\u00fablica<\/strong> organizada el pasado 22 de marzo por la Asociaci\u00f3n de Empresas\u00a0 Contratistas con las Administraciones P\u00fablicas (<strong>AESMIDE<\/strong>) en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado, encuentro que ya se ha convertido en una referencia a nivel nacional sobre la materia. Se trataron las novedades en materia de contrataci\u00f3n electr\u00f3nica y en particular, el despacho abord\u00f3 la cuesti\u00f3n del expediente electr\u00f3nico, la transparencia y el secreto comercial que est\u00e1 generando una gran problem\u00e1tica pr\u00e1ctica desde la aprobaci\u00f3n de la\u00a0 Ley 1\/2019, de 20 de febrero, de Secretos Empresariales.<\/p>\n<p><img decoding=\"async\" style=\"width: 300px; height: 175px;\" src=\"\/wp-content\/uploads\/common\/dsc_0203-1024x681.jpg\" alt=\"\" \/>\u00a0\u00a0<img decoding=\"async\" style=\"width: 300px; height: 189px;\" src=\"\/wp-content\/uploads\/common\/ok_-_copia.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica<\/p>\n","protected":false},"author":1,"featured_media":2443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toda &amp; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toda &amp; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-28T10:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-24T08:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\"},\"headline\":\"Toda &#038; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica\",\"datePublished\":\"2019-03-28T10:45:00+00:00\",\"dateModified\":\"2024-12-24T08:44:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/\"},\"wordCount\":152,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/dsc-0246.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/\",\"name\":\"Toda & Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/dsc-0246.jpg\",\"datePublished\":\"2019-03-28T10:45:00+00:00\",\"dateModified\":\"2024-12-24T08:44:10+00:00\",\"description\":\"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/dsc-0246.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/dsc-0246.jpg\",\"width\":2560,\"height\":1456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toda &#038; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/www.todanelo.com\"],\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toda & Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados","description":"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/","og_locale":"fr_FR","og_type":"article","og_title":"Toda & Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados","og_description":"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica","og_url":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/","og_site_name":"Toda &amp; Nel-lo Abogados","article_published_time":"2019-03-28T10:45:00+00:00","article_modified_time":"2024-12-24T08:44:10+00:00","og_image":[{"width":2560,"height":1456,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg","type":"image\/jpeg"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"emfasi","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#article","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/"},"author":{"name":"emfasi","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a"},"headline":"Toda &#038; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica","datePublished":"2019-03-28T10:45:00+00:00","dateModified":"2024-12-24T08:44:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/"},"wordCount":152,"commentCount":10,"publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg","articleSection":["Sin categorizar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/","url":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/","name":"Toda & Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg","datePublished":"2019-03-28T10:45:00+00:00","dateModified":"2024-12-24T08:44:10+00:00","description":"Las jornadas sobre materias de Contrataci\u00f3n P\u00fablica, organizadas por AESMIDE en colaboraci\u00f3n con el Instituto Universitario Guti\u00e9rrez Mellado se centraron en las novedades en materia de contrataci\u00f3n electr\u00f3nica","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/dsc-0246.jpg","width":2560,"height":1456},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/toda-nel-lo-participa-en-la-vii-jornada-sobre-materias-de-contratacion-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Toda &#038; Nel-lo participa en la VII jornada sobre materias de Contrataci\u00f3n P\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/fr\/#website","url":"https:\/\/www.todanelo.com\/fr\/","name":"Toda &amp; Nel-lo Abogados","description":"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/fr\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a","name":"emfasi","sameAs":["https:\/\/www.todanelo.com"],"url":"https:\/\/www.todanelo.com\/fr\/noticias\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts\/2442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts\/2442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media\/2443"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media?parent=2442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/categories?post=2442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/tags?post=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}