{"id":2434,"date":"2019-05-27T15:30:00","date_gmt":"2019-05-27T15:30:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/blog\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/"},"modified":"2019-05-27T15:30:00","modified_gmt":"2019-05-27T15:30:00","slug":"jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019","status":"publish","type":"post","link":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/","title":{"rendered":"JORNADA Toda &#038; Nel-lo: La fiscalidad de las relaciones laborales en 2019"},"content":{"rendered":"<p><strong>\u00bfQu\u00e9 es una renta irregular y qu\u00e9 requisitos debe cumplir?<\/strong> <strong>\u00bfQu\u00e9 obligaciones y responsabilidades asume el empleador al retener sobre los salarios?<\/strong> \u00bfY las que asumen los empleados? \u00bfHasta qu\u00e9 punto est\u00e1 exenta (y es deducible) una indemnizaci\u00f3n por despido de un trabajador? \u00bfY para un directivo? \u00bfSi una renta est\u00e1 exenta de impuestos, ello implica una autom\u00e1tica exoneraci\u00f3n de cotizaci\u00f3n en la Seguridad Social? \u00bfCu\u00e1l es la situaci\u00f3n fiscal y de seguridad social de un expatriado? \u00bfY la del impatriado? En general, \u00bfc\u00f3mo puedo retener el talento en mi empresa sin incrementar los costes empresariales y c\u00f3mo conviene implementar un Plan de Compensaci\u00f3n Flexible o un Programa de Incentivos eficiente y efectivo?<\/p>\n<p>La reforma fiscal de 2015 supuso un cambio de paradigma en el seno de la fiscalidad laboral, introduciendo fuertes cortapisas a una fiscalidad ventajosa en los despidos, y limitando mucho la posibilidad de beneficiarse regularmente de beneficios fiscales en los Planes de \u201cstock options\u201d o de cualquier premio o incentivo retributivo indexado a resultados plurianuales. Adem\u00e1s, las nuevas reglas que se introdujeron no s\u00f3lo se ci\u00f1eron al IRPF y a las obligaciones de retenci\u00f3n, sino tambi\u00e9n la Impuesto sobre Sociedades, motivo por el cual un empresario se puede ver compelido por m\u00faltiples v\u00edas o figuras impositivas.<\/p>\n<p>Por otro lado, una vez asentados las pr\u00e1cticas administrativas y criterios interpretativos tras casi un lustro de funcionamiento de las nuevas reglas, procede examinar la actual legislaci\u00f3n en materia de fiscalidad laboral y de seguridad social a la luz de las actuales tendencias del mercado: deslocalizaci\u00f3n y alta movilidad internacional de los trabajadores; retribuci\u00f3n por objetivos y mayor compartimento de riesgos-beneficios entre empleador y empleado; y alta competencia por el talento en determinados sectores o perfiles.<\/p>\n<p>\u00a0<\/p>\n<p><u>Organizamos una sesi\u00f3n informativa en la que se analizar\u00e1n de forma pr\u00e1ctica y desde una \u00f3ptica global (laboral, fiscal y seguridad social) las dudas m\u00e1s frecuentes en esta materia y c\u00f3mo deben abordarse para evitar los riesgos, tanto para el empleado como para el empleador.<\/u><\/p>\n<p>\u00a0<\/p>\n<h2>Programa\u00a0<\/h2>\n<p>9.00h &#8211; Recepci\u00f3n y caf\u00e9 de bienvenida<br \/>\n\t9.15h &#8211; Inicio de la jornada<br \/>\n\t11.00h &#8211; Conclusiones y coloquio<br \/>\n\t11.15h &#8211; Fin de la Jornada<\/p>\n<p>\u00a0<\/p>\n<h2>Ponentes<\/h2>\n<p><strong>D\u00eddac Ripoll\u00e8s<\/strong>. Socio responsable del \u00e1rea de Derecho Laboral de Toda &#038; Nel-lo.<br \/>\n\t<strong>Albert Mestres<\/strong>. Counsel responsable del \u00e1rea de Fiscalidad Internacional de Toda &#038; Nel-lo.<br \/>\n\t<strong>Mireia de Pol<\/strong>. Abogada senior de Toda &#038; Nel-lo, especialista en procedimientos tributarios.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>El aforo es limitado, por lo que para la inscripci\u00f3n es necesario enviar un correo electr\u00f3nico a <strong><u><a href=\"mailto:comunicacion@todanelo.com?subject=Confirmaci%C3%B3n%20asistencia%20Jornada%20Fiscalidad%20en%20las%20relaciones%20laborales\">comunicacion@todanelo.com<\/a><\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l&rsquo;Eixample<\/p>\n","protected":false},"author":1,"featured_media":2435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JORNADA Toda &amp; Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l&#039;Eixample\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JORNADA Toda &amp; Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l&#039;Eixample\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-27T15:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"853\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\"},\"headline\":\"JORNADA Toda &#038; Nel-lo: La fiscalidad de las relaciones laborales en 2019\",\"datePublished\":\"2019-05-27T15:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/\"},\"wordCount\":451,\"commentCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/jornada-web-0.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/\",\"name\":\"JORNADA Toda & Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/jornada-web-0.jpg\",\"datePublished\":\"2019-05-27T15:30:00+00:00\",\"description\":\"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l'Eixample\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/jornada-web-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/jornada-web-0.jpg\",\"width\":853,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JORNADA Toda &#038; Nel-lo: La fiscalidad de las relaciones laborales en 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/www.todanelo.com\"],\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/noticias\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JORNADA Toda & Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados","description":"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l'Eixample","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"JORNADA Toda & Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados","og_description":"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l'Eixample","og_url":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/","og_site_name":"Toda &amp; Nel-lo Abogados","article_published_time":"2019-05-27T15:30:00+00:00","og_image":[{"width":853,"height":540,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg","type":"image\/jpeg"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"emfasi","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#article","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/"},"author":{"name":"emfasi","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a"},"headline":"JORNADA Toda &#038; Nel-lo: La fiscalidad de las relaciones laborales en 2019","datePublished":"2019-05-27T15:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/"},"wordCount":451,"commentCount":18,"publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/","url":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/","name":"JORNADA Toda & Nel-lo: La fiscalidad de las relaciones laborales en 2019 - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg","datePublished":"2019-05-27T15:30:00+00:00","description":"Jueves 13 de junio 2019, de 9 a 11.15h, en El Principal de l'Eixample","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/jornada-web-0.jpg","width":853,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/fr\/noticias\/jornada-toda-nel-lo-la-fiscalidad-de-las-relaciones-laborales-en-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"JORNADA Toda &#038; Nel-lo: La fiscalidad de las relaciones laborales en 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/fr\/#website","url":"https:\/\/www.todanelo.com\/fr\/","name":"Toda &amp; Nel-lo Abogados","description":"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/fr\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a","name":"emfasi","sameAs":["https:\/\/www.todanelo.com"],"url":"https:\/\/www.todanelo.com\/fr\/noticias\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/comments?post=2434"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/posts\/2434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media\/2435"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media?parent=2434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/categories?post=2434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/tags?post=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}