{"id":2767,"date":"2021-11-10T15:30:00","date_gmt":"2021-11-10T15:30:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/legal-news\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/"},"modified":"2021-11-10T15:30:00","modified_gmt":"2021-11-10T15:30:00","slug":"fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad","status":"publish","type":"legal-news","link":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/","title":{"rendered":"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad"},"content":{"rendered":"<p>Recientemente, se han producido importantes modificaciones en el derecho de las personas con discapacidad tanto a nivel estatal como en Catalu\u00f1a, y ello a ra\u00edz de la entrada en vigor de la Ley 8\/2021, de 2 de junio, por la que se reforma la legislaci\u00f3n civil y procesal y tambi\u00e9n el Decreto Ley 19\/2021, de 31 de agosto, por el que se adapta el C\u00f3digo Civil de Catalu\u00f1a a la reforma del procedimiento de modificaci\u00f3n judicial de la capacidad.<\/p>\n<p>A continuaci\u00f3n, trataremos de resumir brevemente las m\u00e1s relevantes.<\/p>\n<h3>\u00a0<\/h3>\n<h3>Modificaci\u00f3n de la normativa estatal:<\/h3>\n<p>La reforma introducida en la legislaci\u00f3n estatal ha supuesto un nuevo paso hacia la progresiva adecuaci\u00f3n de nuestro ordenamiento jur\u00eddico a la Convenci\u00f3n Internacional sobre los Derechos de las Personas con Discapacidad, aprobada en Nueva York en 2006, norma que ha venido orientando las resoluciones dictadas por nuestros tribunales en esta materia y a la que se ha intentado ir adecuando nuestro ordenamiento a trav\u00e9s de distintas modificaciones legislativas.<\/p>\n<p>En este sentido, con dicha modificaci\u00f3n, se concibe ahora un r\u00e9gimen de apoyo para el ejercicio de la capacidad jur\u00eddica de las personas con discapacidad que incluye modificaciones, tanto en el \u00e1mbito civil como procesal, estableci\u00e9ndose un nuevo sistema de apoyo a las personas con discapacidad. La idea que orienta <strong>este nuevo sistema<\/strong>, bajo la consideraci\u00f3n de que todas las personas son titulares del derecho a la toma de sus propias decisiones, es que <strong>la capacidad jur\u00eddica resulta inherente a la condici\u00f3n humana<\/strong> y, por tanto, <strong>no puede perderse ni modificarse<\/strong>.<\/p>\n<p>As\u00ed, la nueva regulaci\u00f3n <strong>elimina<\/strong>, por lo tanto, el <strong>concepto cl\u00e1sico de incapacitaci\u00f3n<\/strong>, y la representaci\u00f3n deja de ser la forma de apoyo a la persona incapacitada. En contraposici\u00f3n, el nuevo sistema prev\u00e9 el apoyo de la persona en el ejercicio de su capacidad. Este apoyo se despliega en actuaciones de distinto tipo: acompa\u00f1amiento amistoso, ayuda t\u00e9cnica en la comunicaci\u00f3n de declaraciones de voluntad, consejo, toma de decisiones delegadas y como \u00faltima ratio, representaci\u00f3n en la toma de decisiones.<\/p>\n<p>Para ello, <strong>se eliminan las instituciones de la tutela<\/strong> -hist\u00f3ricamente el centro del procedimiento de incapacitaci\u00f3n-, y de la patria potestad prorrogada y rehabilitada, y <strong>centra la atenci\u00f3n en el desarrollo de la curatela<\/strong>, instituci\u00f3n que pasa a considerarse como la medida judicial id\u00f3nea para el apoyo de las personas con discapacidad.<\/p>\n<p>La curatela se concibe como una instituci\u00f3n de ayuda gradual en el ejercicio de la capacidad jur\u00eddica que precisa que se establezcan los actos concretos para los que la persona requiere de apoyo y, solo en \u00faltimo t\u00e9rmino, se prev\u00e9 la posibilidad de atribuir al curador funciones representativas. Adem\u00e1s, se establece que las medidas de apoyo acordadas ser\u00e1n revisadas peri\u00f3dicamente por la autoridad judicial para garantizar que atiendan adecuadamente a la situaci\u00f3n de la persona.<\/p>\n<p>Por su parte, en el \u00e1mbito procesal, la nueva ley pretende que el sistema previsto en la Ley de la Jurisdicci\u00f3n Voluntaria (\u00abLJV\u00bb) pase a ser el sistema preferente, acudi\u00e9ndose al procedimiento de la Ley de Enjuiciamiento Civil (\u00abLEC\u00bb) solo cuando exista oposici\u00f3n en el expediente previo de jurisdicci\u00f3n voluntaria se regir\u00e1 el procedimiento por lo previsto en la Ley de Enjuiciamiento Civil (\u00abLEC\u00bb).<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<h3>Modificaci\u00f3n de la normativa catalana:<\/h3>\n<p>Tras la reforma estatal, la Generalitat de Catalu\u00f1a se vio obligada a la aprobaci\u00f3n del Decreto Ley 19\/2021, mediante el que viene a resolver de forma provisional el vac\u00edo que deja para los sometidos a la ley sustantiva catalana las profundas modificaciones de orden procedimental introducidas por la mentada ley estatal. El ejecutivo catal\u00e1n se ha impuesto la obligaci\u00f3n de aprobar en el plazo de doce meses una modificaci\u00f3n completa del Libro Segundo del C\u00f3digo Civil de Catalu\u00f1a (CCCat).<\/p>\n<p>Es decir, el Decreto Ley 19\/2021 se centra en salvar transitoriamente el vac\u00edo generado por la modificaci\u00f3n de la LJV y la LEC a trav\u00e9s de la reformulaci\u00f3n de los art\u00edculos 226-1 a 226-7 del CCCat.<\/p>\n<p>Mediante esta reforma, tambi\u00e9n<strong> se eliminan las figuras de la tutela y la potestad parental prorrogada<\/strong>, rehabilitada, pero difiere de la regulaci\u00f3n estatal al eliminar la curatela y consagrar la figura de la asistencia como el instrumento principal mediante el que prestar apoyo a la persona con discapacidad.<\/p>\n<p>De modo similar que la curatela en la legislaci\u00f3n com\u00fan, la asistencia en Catalu\u00f1a se concibe como una figura flexible que debe ser aplicada como un abanico de facultades en funci\u00f3n de las necesidades que precise la persona incapaz.<\/p>\n<p>El nuevo articulado prev\u00e9 dos formas de designaci\u00f3n de la asistencia: i) por designaci\u00f3n judicial, mediante solicitud del propio interesado o de las personas legitimadas, y ii) por designaci\u00f3n notarial por parte de la propia persona.<\/p>\n<p>Esta posibilidad de designaci\u00f3n notarial es una de las reformas m\u00e1s relevantes puesto que, ahora, <strong>una persona en previsi\u00f3n o apreciaci\u00f3n de un estado de incapacidad podr\u00e1 ordenar en escritura p\u00fablica<\/strong> &#8211; que deber\u00e1 inscribir en el registro civil \u2013 la designaci\u00f3n de las personas que deber\u00e1n asistirla y el contenido y funcionamiento de la asistencia. En circunstancias excepcionales, la autoridad judicial podr\u00e1 prescindir de esta designaci\u00f3n o modificarla si las circunstancias lo aconsejan.<\/p>\n<p>En el procedimiento que conduzca a la designaci\u00f3n judicial de la persona que deba ejercer la asistencia ser\u00e1 necesario respetar la voluntad, deseos y preferencias de la persona, debiendo recabarse la mayor informaci\u00f3n posible de las personas de su confianza a fin de conocer esta voluntad si el interesando no pudiera expresarla. El nombramiento deber\u00e1 inscribirse en el registro civil y deber\u00e1 ser revisado de oficio, con car\u00e1cter general, cada tres a\u00f1os.<\/p>\n<p>A fin de compatibilizar los nuevos preceptos con los que persisten en el sistema, el Decreto establece que <strong>todas las referencias hechas a la tutela, curatela y potestad prorrogada se han de entender hechas al nuevo sistema<\/strong>.\u00a0 A su vez, no se podr\u00e1n constituir nuevas tutelas, curatelas ni potestades parentales a partir de la entrada en vigor de esta norma y las constituidas anteriormente se mantienen en vigor hasta su revisi\u00f3n (adaptaci\u00f3n al nuevo r\u00e9gimen). En este sentido, la revisi\u00f3n podr\u00e1 ser solicitada en cualquier momento por las personas sometidas a la medida y las que ejercen alg\u00fan cargo sobre ellas. Si esta solicitud no se realiza, la revisi\u00f3n se har\u00e1 de oficio por la autoridad judicial o a instancia del Ministerio Fiscal, dentro del plazo de tres a\u00f1os desde la entrada en vigor de este Decreto Ley.<\/p>\n<p>Las modificaciones son, pues, sustanciales, por lo que habr\u00e1 que ver c\u00f3mo se van implementando a partir de ahora y si, como se pretende, se van a salvaguardar los intereses de la persona \u201cincapaz\u201d y si esta se ver\u00e1 completamente protegida.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad<\/p>\n","protected":false},"featured_media":2768,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2767","legal-news","type-legal-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/incapacitacion-judicial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/\",\"name\":\"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/incapacitacion-judicial.jpg\",\"datePublished\":\"2021-11-10T15:30:00+00:00\",\"description\":\"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/incapacitacion-judicial.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/incapacitacion-judicial.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad jur\u00eddica\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados","description":"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/","og_locale":"fr_FR","og_type":"article","og_title":"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados","og_description":"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad","og_url":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/","og_site_name":"Toda &amp; Nel-lo Abogados","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/incapacitacion-judicial.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/","url":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/","name":"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/incapacitacion-judicial.jpg","datePublished":"2021-11-10T15:30:00+00:00","description":"Se modifican un conjunto de importantes leyes, y afectar\u00e1 a 4,5 millones de personas pertenecientes al colectivo con discapacidad","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/incapacitacion-judicial.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/incapacitacion-judicial.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/fin-de-la-incapacitacion-judicial-de-personas-con-discapacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualidad jur\u00eddica","item":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/"},{"@type":"ListItem","position":3,"name":"Fin de la incapacitaci\u00f3n judicial de personas con discapacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/fr\/#website","url":"https:\/\/www.todanelo.com\/fr\/","name":"Toda &amp; Nel-lo Abogados","description":"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/fr\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news"}],"about":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/types\/legal-news"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news\/2767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media\/2768"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media?parent=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}