{"id":2683,"date":"2022-11-23T16:45:00","date_gmt":"2022-11-23T16:45:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/legal-news\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/"},"modified":"2022-11-23T16:45:00","modified_gmt":"2022-11-23T16:45:00","slug":"el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las","status":"publish","type":"legal-news","link":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/","title":{"rendered":"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas"},"content":{"rendered":"<p>El Proyecto de Ley de protecci\u00f3n del informante ha iniciado su tramitaci\u00f3n en el Congreso recogiendo importantes repercusiones en cuanto a la gesti\u00f3n de canales de denuncias de empresas, entidades y administraciones p\u00fablicas.<\/p>\n<p>En este sentido, el Proyecto de Ley incorpora al derecho espa\u00f1ol la Directiva 2019\/1937 relativa a la protecci\u00f3n de las personas que informen sobre infracciones del Derecho de la Uni\u00f3n, que establece la <strong>obligaci\u00f3n<\/strong> para empresas y entidades (fundaciones, asociaciones, etc.) que<strong> empleen a 50 o m\u00e1s trabajadores <\/strong>de disponer de un <strong>canal de denuncias<\/strong>.<\/p>\n<p>En cada empresa, <strong>el \u00f3rgano de administraci\u00f3n ser\u00e1 responsable de la implantaci\u00f3n y del funcionamiento <\/strong>de su canal de denuncias y deber\u00e1 garantizar la prohibici\u00f3n de represalias y la confidencialidad del informante, as\u00ed como las denuncias an\u00f3nimas.\u00a0\u00a0<\/p>\n<p>Todo ello deber\u00e1 estar <strong>recogido en una normativa espec\u00edfica interna <\/strong>en la que se regule la gesti\u00f3n del canal, el tratamiento de datos y la adopci\u00f3n de decisiones.<\/p>\n<p>El Proyecto de Ley prev\u00e9 que el canal de denuncias pueda ser gestionado por un <strong>tercero externo que garantice la confidencialidad y la independencia<\/strong> en la gesti\u00f3n del canal.<\/p>\n<p>Es necesario tener en cuenta que, adem\u00e1s de las empresas de 50 o m\u00e1s trabajadores, <strong>est\u00e1n obligadas a disponer de un canal de denuncias las empresas o entidades sujetas a la normativa de servicios<\/strong>, productos y mercados financieros, y las sujetas a la normativa de prevenci\u00f3n del blanqueo de capitales y financiaci\u00f3n del terrorismo, cualquiera que sea su n\u00famero de trabajadores. Tambi\u00e9n los partidos pol\u00edticos, sindicatos, organizaciones empresariales y fundaciones vinculadas.<\/p>\n<p>En cuanto al<strong> sector p\u00fablico<\/strong>, la obligaci\u00f3n de disponer de un canal de denuncias es general incluyendo la Administraci\u00f3n General del Estado, las Administraciones auton\u00f3micas, locales, universidades, corporaciones de derecho p\u00fablico, fundaciones, sociedades mercantiles de participaci\u00f3n p\u00fablica mayoritaria, etc.<\/p>\n<p>El incumplimiento de la obligaci\u00f3n de implantar un canal de denuncia puede conllevar <strong>sanciones<\/strong> de hasta <strong>un mill\u00f3n de euros<\/strong>.<\/p>\n<p>Todo ello hace necesario <strong>revisar la necesidad de disponer de canal de denuncias<\/strong>, la adecuaci\u00f3n de los canales actualmente existentes a la nueva normativa y la posibilidad de profesionalizarlos, externalizando su gesti\u00f3n para garantizar la confidencialidad, independencia y no represalia.<\/p>\n<p>El<a href=\"https:\/\/www.todanelo.com\/areas-de-practica\/compliance\/corporate-defense-prevencion-penal-para-empresas-y-administradores\" target=\"_blank\" rel=\"noopener\"> \u00e1rea de Compliance de Toda &#038; Nel-lo<\/a> tiene amplia experiencia en asesorar a empresas en el dise\u00f1o, implementaci\u00f3n y gesti\u00f3n operativa de canales de denuncia y ofrece servicios de regulaci\u00f3n y externalizaci\u00f3n de estos.<\/p>\n<h3>\u00a0<\/h3>\n<h3><a href=\"https:\/\/www.todanelo.com\/areas-de-practica\/compliance\/corporate-defense-prevencion-penal-para-empresas-y-administradores\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n y contacto<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.<\/p>\n","protected":false},"featured_media":2684,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2683","legal-news","type-legal-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/pexels-cottonbro-studio-7207362.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/\",\"name\":\"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/pexels-cottonbro-studio-7207362.jpg\",\"datePublished\":\"2022-11-23T16:45:00+00:00\",\"description\":\"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/pexels-cottonbro-studio-7207362.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/pexels-cottonbro-studio-7207362.jpg\",\"width\":1280,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad jur\u00eddica\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/actualite-juridique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados","description":"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/","og_locale":"fr_FR","og_type":"article","og_title":"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados","og_description":"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.","og_url":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/","og_site_name":"Toda &amp; Nel-lo Abogados","og_image":[{"width":1280,"height":718,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/pexels-cottonbro-studio-7207362.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/","url":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/","name":"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/pexels-cottonbro-studio-7207362.jpg","datePublished":"2022-11-23T16:45:00+00:00","description":"El Proyecto de Ley de protecci\u00f3n del informante establece la obligaci\u00f3n para empresas y entidades que empleen a 50 o m\u00e1s trabajadores de disponer de un canal de denuncias.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/pexels-cottonbro-studio-7207362.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/pexels-cottonbro-studio-7207362.jpg","width":1280,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/el-nuevo-proyecto-de-ley-que-afecta-los-canales-de-denuncia-internos-de-las\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualidad jur\u00eddica","item":"https:\/\/www.todanelo.com\/fr\/actualite-juridique\/"},{"@type":"ListItem","position":3,"name":"El nuevo Proyecto de Ley que afecta a los canales de denuncia internos de las empresas"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/fr\/#website","url":"https:\/\/www.todanelo.com\/fr\/","name":"Toda &amp; Nel-lo Abogados","description":"Bureaux juridiques \u00e0 Barcelone et \u00e0 Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/fr\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news\/2683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news"}],"about":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/types\/legal-news"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/legal-news\/2683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media\/2684"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/fr\/wp-json\/wp\/v2\/media?parent=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}