{"id":2460,"date":"2018-11-14T18:30:00","date_gmt":"2018-11-14T18:30:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/blog\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/"},"modified":"2018-11-14T18:30:00","modified_gmt":"2018-11-14T18:30:00","slug":"video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes","status":"publish","type":"post","link":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/","title":{"rendered":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes"},"content":{"rendered":"<p>En el marco del proyecto que iniciamos hace unos meses y que seguimos desarrollando a diario -la apertura de nuestro nuevo Despacho en Madrid-, hemos pedido a algunos de nuestros clientes que nos explicaran qu\u00e9 es para ellos Toda &#038; Nel-lo y cu\u00e1les son, para ellos, los valores que nos hacen \u00fanicos.<\/p>\n<p>Para este <u><a href=\"https:\/\/www.youtube.com\/watch?v=AT7IXLqhB80\" target=\"_blank\" rel=\"noopener\">v\u00eddeo<\/a><\/u> hemos contado con la colaboraci\u00f3n de Ingrid Fornesa, Jos\u00e9 Luis Bonet, Germ\u00e1n Cid, Agust\u00edn Cord\u00f3n, Jos\u00e9 Mar\u00eda Coronas,\u00a0 Jorge Garbajosa, Antonio Gass\u00f3 y Marc Ros.<\/p>\n<p>A todos ellos queremos dar las gracias.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<div class=\"media_embed\">\n<iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/AT7IXLqhB80\" width=\"560\"><\/iframe><\/div>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Toda &#038; Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.<\/p>\n","protected":false},"author":1,"featured_media":2461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"En Toda &amp; Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"En Toda &amp; Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-14T18:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1252\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\"},\"headline\":\"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes\",\"datePublished\":\"2018-11-14T18:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/\"},\"wordCount\":110,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/video-clientes.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/\",\"name\":\"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/video-clientes.png\",\"datePublished\":\"2018-11-14T18:30:00+00:00\",\"description\":\"En Toda & Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/video-clientes.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/video-clientes.png\",\"width\":1252,\"height\":697},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Despacho Jur\u00eddico Barcelona y Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/www.todanelo.com\"],\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados","description":"En Toda & Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/","og_locale":"es_ES","og_type":"article","og_title":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados","og_description":"En Toda & Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.","og_url":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/","og_site_name":"Toda &amp; Nel-lo Abogados","article_published_time":"2018-11-14T18:30:00+00:00","og_image":[{"width":1252,"height":697,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png","type":"image\/png"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"emfasi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#article","isPartOf":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/"},"author":{"name":"emfasi","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a"},"headline":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes","datePublished":"2018-11-14T18:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/"},"wordCount":110,"commentCount":9,"publisher":{"@id":"https:\/\/www.todanelo.com\/es\/#organization"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/","url":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/","name":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png","datePublished":"2018-11-14T18:30:00+00:00","description":"En Toda & Nel-lo, lo mejor que tenemos son nuestros clientes. Por eso, la mejor manera de definir nuestros valores es a trav\u00e9s de sus palabras.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/video-clientes.png","width":1252,"height":697},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/es\/noticias\/video-la-mejor-manera-de-definirnos-es-traves-de-las-palabras-de-nuestros-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/es\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeo: La mejor manera de definirnos es a trav\u00e9s de las palabras de nuestros clientes"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/es\/#website","url":"https:\/\/www.todanelo.com\/es\/","name":"Toda &amp; Nel-lo Abogados","description":"Despacho Jur\u00eddico Barcelona y Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/es\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a","name":"emfasi","sameAs":["https:\/\/www.todanelo.com"],"url":"https:\/\/www.todanelo.com\/es\/noticias\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts\/2460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/comments?post=2460"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts\/2460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/media\/2461"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/media?parent=2460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/categories?post=2460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/tags?post=2460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}