{"id":2456,"date":"2018-11-27T11:15:00","date_gmt":"2018-11-27T11:15:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/blog\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/"},"modified":"2018-11-27T11:15:00","modified_gmt":"2018-11-27T11:15:00","slug":"best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019","status":"publish","type":"post","link":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/","title":{"rendered":"Best Lawyers reconoce a dos abogados de Toda &#038; Nel-lo en su edici\u00f3n de 2019"},"content":{"rendered":"<p><a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/josep-m-balcells-cabanas\" target=\"_blank\" rel=\"noopener\"><strong>Josep M. Balcells<\/strong><\/a> y <strong><a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/javier-hernandez-hernandez\" target=\"_blank\" rel=\"noopener\">Javier Hern\u00e1ndez<\/a><\/strong>, socio y counsel, respectivamente, del \u00e1rea de Mercantil de Toda &#038; Nel-lo, aparecen en la 11\u00aa edici\u00f3n de la publicaci\u00f3n\u00a0 <a href=\"http:\/\/www.bestlawyers.com\" target=\"_blank\" rel=\"noopener\"><u>Best Lawyers\u00ae<\/u><\/a> para Espa\u00f1a, un ranking de profesionales elaborado <strong>con las recomendaciones de sus compa\u00f1eros de profesi\u00f3n<\/strong>. Son los propios \u201cpeers\u201d, quienes valoran la labor profesional de los candidatos y eligen a los premiados. Ambos abogados figuraban en la publicaci\u00f3n desde hace a\u00f1os; en concreto, desde 2013 en el caso de Josep M. Balcells, y desde 2015 en el caso de Javier Hern\u00e1ndez.<\/p>\n<p>Josep M. Balcells es Socio Director de las \u00e1reas Mercantil e Internacional del Despacho; abogado especialista en Derecho Comercial y Societario, as\u00ed como en Derecho de los Negocios y Contractual internacional. Posee amplia experiencia en el asesoramiento a numerosas empresas espa\u00f1olas y extranjeras en materia de operaciones societarias, contrataci\u00f3n y operativa comercial y morosidad.\u00a0 Igualmente, se ha especializado en materia de distribuci\u00f3n comercial internacional (agencia, franquicia y distribuci\u00f3n), as\u00ed como en el sector energ\u00e9tico, sector \u201cretail\u201d y en automoci\u00f3n, en sus respectivas regulaciones sectoriales.<\/p>\n<p>Por su parte, la pr\u00e1ctica profesional de Javier Hern\u00e1ndez se ha centrado principalmente en el \u00e1rea de las fusiones y adquisiciones, financiaci\u00f3n corporativa y de proyectos, reestructuraci\u00f3n de deuda y mercado de capitales. Ha participado en operaciones de relevancia en diversas \u00e1reas de su pr\u00e1ctica profesional y su experiencia incluye una amplia variedad de operaciones a nivel nacional e internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los abogados de Toda &#038; Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&#038;A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.<\/p>\n","protected":false},"author":1,"featured_media":2457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Best Lawyers reconoce a dos abogados de Toda &amp; Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Los abogados de Toda &amp; Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&amp;A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Best Lawyers reconoce a dos abogados de Toda &amp; Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Los abogados de Toda &amp; Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&amp;A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-27T11:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\"},\"headline\":\"Best Lawyers reconoce a dos abogados de Toda &#038; Nel-lo en su edici\u00f3n de 2019\",\"datePublished\":\"2018-11-27T11:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/\"},\"wordCount\":263,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/best-lawyers-0.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/\",\"name\":\"Best Lawyers reconoce a dos abogados de Toda & Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/best-lawyers-0.png\",\"datePublished\":\"2018-11-27T11:15:00+00:00\",\"description\":\"Los abogados de Toda & Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/best-lawyers-0.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/best-lawyers-0.png\",\"width\":1240,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Best Lawyers reconoce a dos abogados de Toda &#038; Nel-lo en su edici\u00f3n de 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Despacho Jur\u00eddico Barcelona y Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/www.todanelo.com\"],\"url\":\"https:\\\/\\\/www.todanelo.com\\\/es\\\/noticias\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Best Lawyers reconoce a dos abogados de Toda & Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados","description":"Los abogados de Toda & Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Best Lawyers reconoce a dos abogados de Toda & Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados","og_description":"Los abogados de Toda & Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.","og_url":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/","og_site_name":"Toda &amp; Nel-lo Abogados","article_published_time":"2018-11-27T11:15:00+00:00","og_image":[{"width":1240,"height":721,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png","type":"image\/png"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"emfasi","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#article","isPartOf":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/"},"author":{"name":"emfasi","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a"},"headline":"Best Lawyers reconoce a dos abogados de Toda &#038; Nel-lo en su edici\u00f3n de 2019","datePublished":"2018-11-27T11:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/"},"wordCount":263,"commentCount":9,"publisher":{"@id":"https:\/\/www.todanelo.com\/es\/#organization"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/","url":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/","name":"Best Lawyers reconoce a dos abogados de Toda & Nel-lo en su edici\u00f3n de 2019 - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png","datePublished":"2018-11-27T11:15:00+00:00","description":"Los abogados de Toda & Nel-lo Josep M. Balcells y Javier Hern\u00e1ndez, ambos especialistas en la pr\u00e1ctica de Derecho Mercantil, Societario y M&A, figuran una vez m\u00e1s en la lista de Best Lawyers\u00ae en Espa\u00f1a.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/best-lawyers-0.png","width":1240,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/es\/noticias\/best-lawyers-reconoce-dos-abogados-de-toda-nel-lo-en-su-edicion-de-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Best Lawyers reconoce a dos abogados de Toda &#038; Nel-lo en su edici\u00f3n de 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/es\/#website","url":"https:\/\/www.todanelo.com\/es\/","name":"Toda &amp; Nel-lo Abogados","description":"Despacho Jur\u00eddico Barcelona y Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/es\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.todanelo.com\/es\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a","name":"emfasi","sameAs":["https:\/\/www.todanelo.com"],"url":"https:\/\/www.todanelo.com\/es\/noticias\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts\/2456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/comments?post=2456"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/posts\/2456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/media\/2457"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/media?parent=2456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/categories?post=2456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todanelo.com\/es\/wp-json\/wp\/v2\/tags?post=2456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}