{"id":2430,"date":"2019-09-12T07:45:00","date_gmt":"2019-09-12T07:45:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/blog\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/"},"modified":"2019-09-12T07:45:00","modified_gmt":"2019-09-12T07:45:00","slug":"el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer","status":"publish","type":"post","link":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/","title":{"rendered":"El abogado de Toda &#038; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer"},"content":{"rendered":"<p><a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/albert-mestres-llort\" target=\"_blank\" rel=\"noopener\"><strong>Albert Mestres<\/strong><\/a>, counsel de Derecho Tributario de Toda &#038; Nel-lo, fue uno de los finalistas de los premios \u2018<a href=\"http:\/\/www.iberianlawyer.com\/awards-menutop\/40-under-forty-awards#presentation\" target=\"_blank\" rel=\"noopener\">40\u00a0Under Forty<\/a>\u2019 de 2019 que otorga Iberian Lawyer y que reconocen el trabajo de los abogados menores de cuarenta a\u00f1os m\u00e1s destacados en Espa\u00f1a y Portugal en sus \u00e1reas de especializaci\u00f3n.<\/p>\n<p>En el caso de Albert Mestres, ha sido nombrado finalista como <strong>abogado destacado en la categor\u00eda de Fiscal<\/strong>, junto a otros 18 tributaristas espa\u00f1oles.<\/p>\n<p>El abogado de Toda &#038; Nel-lo est\u00e1 especializado en Derecho Tributario, y dirige en el despacho el \u00e1rea de fiscalidad internacional y asesoramiento transaccional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.<\/p>\n","protected":false},"author":1,"featured_media":2431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-2430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El abogado de Toda &amp; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El abogado de Toda &amp; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-12T07:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"686\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"emfasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emfasi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/\"},\"author\":{\"name\":\"emfasi\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\"},\"headline\":\"El abogado de Toda &#038; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer\",\"datePublished\":\"2019-09-12T07:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/\"},\"wordCount\":113,\"commentCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/albert-mestres-finalista-40-under-40-0.png\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/\",\"name\":\"El abogado de Toda & Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/albert-mestres-finalista-40-under-40-0.png\",\"datePublished\":\"2019-09-12T07:45:00+00:00\",\"description\":\"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/albert-mestres-finalista-40-under-40-0.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/albert-mestres-finalista-40-under-40-0.png\",\"width\":686,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El abogado de Toda &#038; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Legal firm in Barcelona and Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/person\\\/403e6ed9d856044c44f52763ead94c6a\",\"name\":\"emfasi\",\"sameAs\":[\"https:\\\/\\\/www.todanelo.com\"],\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/noticias\\\/author\\\/emfasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El abogado de Toda & Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados","description":"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/","og_locale":"en_US","og_type":"article","og_title":"El abogado de Toda & Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados","og_description":"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.","og_url":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/","og_site_name":"Toda &amp; Nel-lo Abogados","article_published_time":"2019-09-12T07:45:00+00:00","og_image":[{"width":686,"height":420,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png","type":"image\/png"}],"author":"emfasi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emfasi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#article","isPartOf":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/"},"author":{"name":"emfasi","@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a"},"headline":"El abogado de Toda &#038; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer","datePublished":"2019-09-12T07:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/"},"wordCount":113,"commentCount":18,"publisher":{"@id":"https:\/\/www.todanelo.com\/en\/#organization"},"image":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/","url":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/","name":"El abogado de Toda & Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png","datePublished":"2019-09-12T07:45:00+00:00","description":"Albert Mestres ha sido en la edici\u00f3n de 2019 uno de los finalistas de los premios \u2018Forty Under 40\u2019 que otorga Iberian Lawyer para la categor\u00eda de Fiscal.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/albert-mestres-finalista-40-under-40-0.png","width":686,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/en\/noticias\/el-abogado-de-toda-nel-lo-albert-mestres-finalista-de-forty-under-40-de-iberian-lawyer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/en\/"},{"@type":"ListItem","position":2,"name":"El abogado de Toda &#038; Nel-lo Albert Mestres, finalista de Forty Under 40 de Iberian Lawyer"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/en\/#website","url":"https:\/\/www.todanelo.com\/en\/","name":"Toda &amp; Nel-lo Abogados","description":"Legal firm in Barcelona and Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/en\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/person\/403e6ed9d856044c44f52763ead94c6a","name":"emfasi","sameAs":["https:\/\/www.todanelo.com"],"url":"https:\/\/www.todanelo.com\/en\/noticias\/author\/emfasi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/posts\/2430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/comments?post=2430"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/posts\/2430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/media\/2431"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/media?parent=2430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/categories?post=2430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/tags?post=2430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}