{"id":2771,"date":"2021-11-09T15:45:00","date_gmt":"2021-11-09T15:45:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/legal-news\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/"},"modified":"2021-11-09T15:45:00","modified_gmt":"2021-11-09T15:45:00","slug":"nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables","status":"publish","type":"legal-news","link":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/","title":{"rendered":"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas"},"content":{"rendered":"<p>El pasado 27 de octubre se public\u00f3 en el Diari Oficial de la Generalitat de Catalunya (DOGC) el <strong>Decreto-Ley 24\/2021, de 26 de octubre, de aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas<\/strong>.<\/p>\n<p><strong>La medida principal <\/strong>del Decreto-Ley, que entr\u00f3 en vigor al d\u00eda siguiente de su publicaci\u00f3n, es la modificaci\u00f3n del Decreto ley 16\/2009, de 26 de noviembre, de medidas urgentes para la emergencia clim\u00e1tica y el impulso a las energ\u00edas renovables, para <strong>introducir medidas que mejoren la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables<\/strong>, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.<\/p>\n<p>Al respecto, es de destacar que <strong>el Decreto-Ley introduce un nuevo art\u00edculo<\/strong>, el 9bis, al Decreto Ley 16\/2019, de 26 de noviembre, en virtud del cual se establece que, en los <strong>proyectos de parques e\u00f3licos y plantas solares fotovoltaicas de potencia superior a 5 MW<\/strong>, situados en tierra y en suelo no urbanizable, se requiere que el promotor acredite (i) la disponibilidad o compromiso de disponibilidad de m\u00e1s del 50% de los terrenos agr\u00edcolas privados sobre los que se proyecta la instalaci\u00f3n y (ii) haber presentado una oferta de participaci\u00f3n local.<\/p>\n<p>Dicha oferta de participaci\u00f3n local consistir\u00e1 en ofrecer la posibilidad de participar, al menos en un 20% de la propiedad del proyecto o de su financiaci\u00f3n, a las personas f\u00edsicas y jur\u00eddicas, p\u00fablicas o privadas, radicadas en el municipio en que se pretende ubicar la instalaci\u00f3n, o en los municipios lim\u00edtrofes al mismo o los que pertenezcan a la misma comarca.<\/p>\n<p>Por otro lado, el Decreto-Ley tambi\u00e9n tiene por objeto (i) <strong>modificar la Ley 16\/2017, de 1 de agosto, del cambio clim\u00e1tico<\/strong>, para prever los objetivos en materia de generaci\u00f3n renovable, distribuida y participada en el horizonte de 2030, concretar la forma de evitar la ocupaci\u00f3n innecesaria del territorio e incorporar a la planificaci\u00f3n energ\u00e9tica la necesidad que se realice conjuntamente con la planificaci\u00f3n territorial sectorial de las energ\u00edas renovables; (ii) adoptar medidas de simplificaci\u00f3n administrativa en materia de autoconsumo de energ\u00eda el\u00e9ctrica; y (iii) crear la Mesa de Di\u00e1logo Social de las Energ\u00edas Renovables.<\/p>\n<p>El texto \u00edntegro del Decreto-Ley puede consultarse<a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8531\/1876122.pdf\" target=\"_blank\" rel=\"noopener\"> en este enlace<\/a>.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>M\u00e1s informaci\u00f3n<\/strong>: <a href=\"https:\/\/www.todanelo.com\/equipo-profesional\/javier-garcia-trujillo\" target=\"_blank\" rel=\"noopener\">Javier Garc\u00eda<\/a>, socio responsable del \u00e1rea de Derecho P\u00fablico de Toda &#038; Nel-lo.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.<\/p>\n","protected":false},"featured_media":2772,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2771","legal-news","type-legal-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/texas-g541022cbe-1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/\",\"name\":\"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/texas-g541022cbe-1280.jpg\",\"datePublished\":\"2021-11-09T15:45:00+00:00\",\"description\":\"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/texas-g541022cbe-1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/texas-g541022cbe-1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad jur\u00eddica\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/topicality-legal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Legal firm in Barcelona and Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados","description":"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/","og_locale":"en_US","og_type":"article","og_title":"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados","og_description":"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.","og_url":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/","og_site_name":"Toda &amp; Nel-lo Abogados","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/texas-g541022cbe-1280.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/","url":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/","name":"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/texas-g541022cbe-1280.jpg","datePublished":"2021-11-09T15:45:00+00:00","description":"El nuevo Decreto-Ley introduce medidas de mejora de la aceptaci\u00f3n social de los proyectos de energ\u00edas renovables, compatibilizar la actividad agraria con la producci\u00f3n de energ\u00edas renovables y velar por la conservaci\u00f3n de la biodiversidad, la ordenaci\u00f3n territorial y el desarrollo sostenible del medio rural.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/texas-g541022cbe-1280.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/texas-g541022cbe-1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/en\/topicality-legal\/nuevo-decreto-ley-sobre-la-aceleracion-del-despliegue-de-las-energias-renovables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Actualidad jur\u00eddica","item":"https:\/\/www.todanelo.com\/en\/topicality-legal\/"},{"@type":"ListItem","position":3,"name":"Nuevo Decreto Ley sobre la aceleraci\u00f3n del despliegue de las energ\u00edas renovables distribuidas y participadas"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/en\/#website","url":"https:\/\/www.todanelo.com\/en\/","name":"Toda &amp; Nel-lo Abogados","description":"Legal firm in Barcelona and Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/en\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/legal-news\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/legal-news"}],"about":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/types\/legal-news"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/legal-news\/2771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/media\/2772"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/en\/wp-json\/wp\/v2\/media?parent=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}