{"id":2970,"date":"2019-09-30T10:45:00","date_gmt":"2019-09-30T10:45:00","guid":{"rendered":"https:\/\/beta.todanelo.com\/legal-news\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/"},"modified":"2019-09-30T10:45:00","modified_gmt":"2019-09-30T10:45:00","slug":"importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad","status":"publish","type":"legal-news","link":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/","title":{"rendered":"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad"},"content":{"rendered":"<p>Recientemente, el Tribunal Supremo (Pleno de la Sala de lo Civil), en su Sentencia de 2 de julio de 2019, ha interpretado el art\u00edculo 178 bis de la Ley Concursal en relaci\u00f3n con el <strong>beneficio de exoneraci\u00f3n del pasivo insatisfecho<\/strong>.<\/p>\n<p>La exoneraci\u00f3n del pasivo insatisfecho es un <strong>mecanismo de segunda oportunidad<\/strong> <strong>mediante el cual el deudor<\/strong> persona f\u00edsica que cumple con unos requisitos m\u00ednimos puede <strong>verse liberado de la mayor parte de la deuda<\/strong> de la que es titular que no pueda ser cubierta con las cantidades obtenidas en la liquidaci\u00f3n concursal.<\/p>\n<p>A efectos pr\u00e1cticos, debe destacarse que esta Sentencia abre la posibilidad a que el deudor de buena fe que se ha acogido al beneficio de exoneraci\u00f3n en cinco a\u00f1os (art\u00edculo 178 bis 3.5\u00ba LC), pueda ser exonerado de parte de las deudas contra\u00eddas con la Administraci\u00f3n P\u00fablica cuando estas tengan la calificaci\u00f3n de cr\u00e9ditos ordinarios o subordinados (50% de la cuota, intereses, recargos, sanciones).<\/p>\n<p>Asimismo, el Alto Tribunal declara que los cr\u00e9ditos calificados como privilegiados (50% de la cuota) puedan ser incluidos en el plan de pagos de cinco a\u00f1os, conforme a lo previsto en el apartado 6 del art\u00edculo 178-bis LC.<br \/>\n\tPuede consultar el texto \u00edntegro de la sentencia aqu\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.<\/p>\n","protected":false},"featured_media":2971,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2970","legal-news","type-legal-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados<\/title>\n<meta name=\"description\" content=\"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:description\" content=\"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Toda &amp; Nel-lo Abogados\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todanelo.com\/wp-content\/uploads\/procesal-ok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/\",\"name\":\"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/procesal-ok.jpg\",\"datePublished\":\"2019-09-30T10:45:00+00:00\",\"description\":\"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/procesal-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/procesal-ok.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad jur\u00eddica\",\"item\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/actualitat-juridica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"description\":\"Despatx de jur\u00eddic a Barcelona i Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#organization\",\"name\":\"Toda &amp; Nel-lo Abogados\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"contentUrl\":\"https:\\\/\\\/www.todanelo.com\\\/wp-content\\\/uploads\\\/logo-todanelo.png\",\"width\":390,\"height\":161,\"caption\":\"Toda &amp; Nel-lo Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todanelo.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados","description":"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/","og_locale":"ca_ES","og_type":"article","og_title":"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados","og_description":"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.","og_url":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/","og_site_name":"Toda &amp; Nel-lo Abogados","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/procesal-ok.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/","url":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/","name":"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad - Toda &amp; Nel-lo Abogados","isPartOf":{"@id":"https:\/\/www.todanelo.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/#primaryimage"},"image":{"@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/procesal-ok.jpg","datePublished":"2019-09-30T10:45:00+00:00","description":"Este precepto de la Ley Concursal tiene por objeto liberar de las deudas contra\u00eddas por las personas f\u00edsicas, para que tras una fracaso empresarial o personal, tengan la posibilidad de encarrilar nuevamente su vida e incluso de arriesgarse a nuevas iniciativas, sin tener que arrastrar indefinidamente una deuda que no podr\u00e1n satisfacer.","breadcrumb":{"@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/#primaryimage","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/procesal-ok.jpg","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/procesal-ok.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/importante-sentencia-del-ts-en-relacion-con-la-ley-de-segunda-oportunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todanelo.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Actualidad jur\u00eddica","item":"https:\/\/www.todanelo.com\/ca\/actualitat-juridica\/"},{"@type":"ListItem","position":3,"name":"Importante sentencia del TS en relaci\u00f3n con la Ley de Segunda Oportunidad"}]},{"@type":"WebSite","@id":"https:\/\/www.todanelo.com\/ca\/#website","url":"https:\/\/www.todanelo.com\/ca\/","name":"Toda &amp; Nel-lo Abogados","description":"Despatx de jur\u00eddic a Barcelona i Madrid","publisher":{"@id":"https:\/\/www.todanelo.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todanelo.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.todanelo.com\/ca\/#organization","name":"Toda &amp; Nel-lo Abogados","url":"https:\/\/www.todanelo.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.todanelo.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","contentUrl":"https:\/\/www.todanelo.com\/wp-content\/uploads\/logo-todanelo.png","width":390,"height":161,"caption":"Toda &amp; Nel-lo Abogados"},"image":{"@id":"https:\/\/www.todanelo.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/legal-news\/2970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/legal-news"}],"about":[{"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/types\/legal-news"}],"version-history":[{"count":0,"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/legal-news\/2970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/media\/2971"}],"wp:attachment":[{"href":"https:\/\/www.todanelo.com\/ca\/wp-json\/wp\/v2\/media?parent=2970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}